{"id":322,"count":2,"description":"","link":"https:\/\/ornsirin.co.th\/en\/category\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3\/","name":"\u0e02\u0e48\u0e32\u0e27\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23","slug":"%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u0e02\u0e48\u0e32\u0e27\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 Archives - Ornsirin (ORN)<\/title>\n<meta name=\"description\" content=\"\u0e02\u0e48\u0e32\u0e27\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 - Ornsirin (ORN)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ornsirin.co.th\/en\/category\/\u0e02\u0e48\u0e32\u0e27\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e02\u0e48\u0e32\u0e27\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 Archives\" \/>\n<meta property=\"og:description\" content=\"\u0e02\u0e48\u0e32\u0e27\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 - Ornsirin (ORN)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ornsirin.co.th\/en\/category\/\u0e02\u0e48\u0e32\u0e27\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\/\" \/>\n<meta property=\"og:site_name\" content=\"Ornsirin (ORN)\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ornsirin.co.th\/wp-content\/uploads\/2024\/08\/Logo-italic-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"304\" \/>\n\t<meta property=\"og:image:height\" content=\"174\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/ornsirin.co.th\\\/category\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3\\\/\",\"url\":\"https:\\\/\\\/ornsirin.co.th\\\/category\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3\\\/\",\"name\":\"\u0e02\u0e48\u0e32\u0e27\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 Archives - Ornsirin (ORN)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ornsirin.co.th\\\/#website\"},\"description\":\"\u0e02\u0e48\u0e32\u0e27\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 - Ornsirin (ORN)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ornsirin.co.th\\\/category\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ornsirin.co.th\\\/category\\\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ornsirin.co.th\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e02\u0e48\u0e32\u0e27\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ornsirin.co.th\\\/#website\",\"url\":\"https:\\\/\\\/ornsirin.co.th\\\/\",\"name\":\"Ornsirin \u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e17\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2e\u0e21 \u0e0a\u0e47\u0e2d\u0e1b\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c (ORN)\",\"description\":\"\u0e1a\u0e49\u0e32\u0e19 \u0e17\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2e\u0e21 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e19\u0e34\u0e0a\u0e13\u0e4c \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e38\u0e13\",\"publisher\":{\"@id\":\"https:\\\/\\\/ornsirin.co.th\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ornsirin.co.th\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ornsirin.co.th\\\/#organization\",\"name\":\"Ornsirin (ORN)\",\"url\":\"https:\\\/\\\/ornsirin.co.th\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ornsirin.co.th\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ornsirin.co.th\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Logo-italic-1.png\",\"contentUrl\":\"https:\\\/\\\/ornsirin.co.th\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Logo-italic-1.png\",\"width\":304,\"height\":174,\"caption\":\"Ornsirin (ORN)\"},\"image\":{\"@id\":\"https:\\\/\\\/ornsirin.co.th\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ornsirin.chiangmai\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0e02\u0e48\u0e32\u0e27\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 Archives - Ornsirin (ORN)","description":"\u0e02\u0e48\u0e32\u0e27\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 - Ornsirin (ORN)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ornsirin.co.th\/en\/category\/\u0e02\u0e48\u0e32\u0e27\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\/","og_locale":"en_US","og_type":"article","og_title":"\u0e02\u0e48\u0e32\u0e27\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 Archives","og_description":"\u0e02\u0e48\u0e32\u0e27\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 - Ornsirin (ORN)","og_url":"https:\/\/ornsirin.co.th\/en\/category\/\u0e02\u0e48\u0e32\u0e27\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\/","og_site_name":"Ornsirin (ORN)","og_image":[{"width":304,"height":174,"url":"https:\/\/ornsirin.co.th\/wp-content\/uploads\/2024\/08\/Logo-italic-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ornsirin.co.th\/category\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3\/","url":"https:\/\/ornsirin.co.th\/category\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3\/","name":"\u0e02\u0e48\u0e32\u0e27\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 Archives - Ornsirin (ORN)","isPartOf":{"@id":"https:\/\/ornsirin.co.th\/#website"},"description":"\u0e02\u0e48\u0e32\u0e27\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 - Ornsirin (ORN)","breadcrumb":{"@id":"https:\/\/ornsirin.co.th\/category\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/ornsirin.co.th\/category\/%e0%b8%82%e0%b9%88%e0%b8%b2%e0%b8%a7%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ornsirin.co.th\/"},{"@type":"ListItem","position":2,"name":"\u0e02\u0e48\u0e32\u0e27\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23"}]},{"@type":"WebSite","@id":"https:\/\/ornsirin.co.th\/#website","url":"https:\/\/ornsirin.co.th\/","name":"Ornsirin \u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e17\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2e\u0e21 \u0e0a\u0e47\u0e2d\u0e1b\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c (ORN)","description":"\u0e1a\u0e49\u0e32\u0e19 \u0e17\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2e\u0e21 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e19\u0e34\u0e0a\u0e13\u0e4c \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e38\u0e13","publisher":{"@id":"https:\/\/ornsirin.co.th\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ornsirin.co.th\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ornsirin.co.th\/#organization","name":"Ornsirin (ORN)","url":"https:\/\/ornsirin.co.th\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ornsirin.co.th\/#\/schema\/logo\/image\/","url":"https:\/\/ornsirin.co.th\/wp-content\/uploads\/2024\/08\/Logo-italic-1.png","contentUrl":"https:\/\/ornsirin.co.th\/wp-content\/uploads\/2024\/08\/Logo-italic-1.png","width":304,"height":174,"caption":"Ornsirin (ORN)"},"image":{"@id":"https:\/\/ornsirin.co.th\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ornsirin.chiangmai\/"]}]}},"_links":{"self":[{"href":"https:\/\/ornsirin.co.th\/en\/wp-json\/wp\/v2\/categories\/322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ornsirin.co.th\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/ornsirin.co.th\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/ornsirin.co.th\/en\/wp-json\/wp\/v2\/posts?categories=322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}