{"id":40305,"date":"2024-10-21T11:23:34","date_gmt":"2024-10-21T04:23:34","guid":{"rendered":"https:\/\/ornsirin.co.th\/?p=40305"},"modified":"2026-03-17T21:57:08","modified_gmt":"2026-03-17T14:57:08","slug":"%e0%b8%95%e0%b8%81%e0%b9%81%e0%b8%95%e0%b9%88%e0%b8%87%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99","status":"publish","type":"post","link":"https:\/\/ornsirin.co.th\/cn\/%e0%b8%95%e0%b8%81%e0%b9%81%e0%b8%95%e0%b9%88%e0%b8%87%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99\/","title":{"rendered":"\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e44\u0e15\u0e25\u0e4c Nordic 8 \u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e14\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e07\u0e48\u0e32\u0e22 \u0e41\u0e15\u0e48\u0e41\u0e1d\u0e07\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e44\u0e15\u0e25\u0e4c"},"content":{"rendered":"<p>\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01 (Nordic Style) \u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e19\u0e31\u0e49\u0e19\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e35\u0e48\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e07\u0e48\u0e32\u0e22 \u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e15\u0e32 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e43\u0e01\u0e25\u0e49\u0e0a\u0e34\u0e14\u0e01\u0e31\u0e1a\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e43\u0e19\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e19\u0e35\u0e49<\/p>\n<div id=\"attachment_40304\" style=\"width: 939px\" class=\"wp-caption alignnone\"><img fetchpriority=\"high\" decoding=\"async\" aria-describedby=\"caption-attachment-40304\" class=\"wp-image-40304\" src=\"https:\/\/ornsirin.co.th\/wp-content\/uploads\/2024\/10\/%E0%B8%9A%E0%B9%89%E0%B8%B2%E0%B8%99%E0%B9%84%E0%B8%AA%E0%B8%95%E0%B8%A5%E0%B9%8C%E0%B8%99%E0%B8%AD%E0%B8%A3%E0%B9%8C%E0%B8%94%E0%B8%B4%E0%B8%81-scaled.webp\" alt=\"\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\" width=\"929\" height=\"618\">\n<p id=\"caption-attachment-40304\" class=\"wp-caption-text\">\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19<\/p>\n<\/div>\n<ol>\n<li><strong>\u0e42\u0e17\u0e19\u0e2a\u0e35:<\/strong> \u0e43\u0e0a\u0e49\u0e42\u0e17\u0e19\u0e2a\u0e35\u0e2d\u0e48\u0e2d\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e02\u0e32\u0e27 \u0e40\u0e17\u0e32 \u0e40\u0e1a\u0e08 \u0e41\u0e25\u0e30\u0e2a\u0e35\u0e19\u0e49\u0e33\u0e40\u0e07\u0e34\u0e19\u0e2d\u0e48\u0e2d\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e17\u0e35\u0e48\u0e2d\u0e1a\u0e2d\u0e38\u0e48\u0e19\u0e41\u0e25\u0e30\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22<\/li>\n<li><strong>\u0e41\u0e2a\u0e07\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34:<\/strong> \u0e43\u0e0a\u0e49\u0e41\u0e2a\u0e07\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e43\u0e2b\u0e49\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e1c\u0e49\u0e32\u0e21\u0e48\u0e32\u0e19\u0e40\u0e1a\u0e32\u0e41\u0e25\u0e30\u0e42\u0e1b\u0e23\u0e48\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e41\u0e2a\u0e07\u0e2a\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19<\/li>\n<li><strong>\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34:<\/strong> \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e40\u0e0a\u0e48\u0e19 \u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e31\u0e07 \u0e41\u0e25\u0e30\u0e1b\u0e39\u0e19\u0e02\u0e32\u0e27 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e2d\u0e1a\u0e2d\u0e38\u0e48\u0e19<\/li>\n<li><strong>\u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e07\u0e48\u0e32\u0e22:<\/strong> \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e04\u0e27\u0e23\u0e21\u0e35\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e07\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e1f\u0e31\u0e07\u0e01\u0e4c\u0e0a\u0e31\u0e19\u0e17\u0e35\u0e48\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e42\u0e15\u0e4a\u0e30\u0e44\u0e21\u0e49\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e2a\u0e41\u0e01\u0e19\u0e14\u0e34\u0e40\u0e19\u0e40\u0e27\u0e35\u0e22<\/li>\n<li><strong>\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22:<\/strong> \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e19 \u0e21\u0e38\u0e21\u0e2d\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2b\u0e23\u0e37\u0e2d\u0e21\u0e38\u0e21\u0e17\u0e33\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e30\u0e14\u0e27\u0e01<\/li>\n<li><strong>\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e14\u0e49\u0e27\u0e22\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49:<\/strong> \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e37\u0e0a\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e2a\u0e14\u0e0a\u0e37\u0e48\u0e19\u0e41\u0e25\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28<\/li>\n<li><strong>\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1d\u0e35\u0e21\u0e37\u0e2d:<\/strong> \u0e43\u0e0a\u0e49\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e07\u0e32\u0e19\u0e1d\u0e35\u0e21\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e21\u0e35\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e19\u0e49\u0e2d\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e2d\u0e01\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19<\/li>\n<li><strong>\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21:<\/strong> \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e07\u0e48\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e19 \u0e42\u0e04\u0e21\u0e44\u0e1f\u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e23\u0e21\u0e17\u0e35\u0e48\u0e40\u0e19\u0e49\u0e19\u0e42\u0e17\u0e19\u0e2a\u0e35\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34<\/li>\n<\/ol>\n<h2 class=\"ng-star-inserted\"><span class=\"ng-star-inserted\">\u201c\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01\u201d \u0e01\u0e31\u0e1a\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e44\u0e17\u0e22: 4 \u0e02\u0e49\u0e2d\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e39\u0e49 \u0e01\u0e48\u0e2d\u0e19\u0e15\u0e31\u0e14\u0e2a\u0e34\u0e19\u0e43\u0e08\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e44\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e1a\u0e49\u0e32\u0e19\u0e23\u0e49\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e23\u0e31\u0e48\u0e27<\/span><\/h2>\n<p class=\"ng-star-inserted\"><span class=\"ng-star-inserted\">\u0e04\u0e27\u0e32\u0e21\u0e19\u0e34\u0e22\u0e21\u0e02\u0e2d\u0e07\u00a0<\/span><strong class=\"ng-star-inserted\"><span class=\"ng-star-inserted\">\u201c\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01\u201d (Nordic Style)<\/span><\/strong><span class=\"ng-star-inserted\">\u00a0\u0e43\u0e19\u0e44\u0e17\u0e22\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e17\u0e35\u0e48\u0e14\u0e39\u0e21\u0e34\u0e19\u0e34\u0e21\u0e2d\u0e25\u0e41\u0e25\u0e30\u0e2d\u0e1a\u0e2d\u0e38\u0e48\u0e19\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e41\u0e15\u0e48\u0e22\u0e31\u0e07\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e04\u0e33\u0e16\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e27\u0e48\u0e32 \u201c\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e2b\u0e19\u0e32\u0e27\u0e08\u0e30\u0e2d\u0e22\u0e39\u0e48\u0e23\u0e2d\u0e14\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e23\u0e49\u0e2d\u0e19\u0e41\u0e25\u0e30\u0e1d\u0e19\u0e0a\u0e38\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e08\u0e23\u0e34\u0e07\u0e2b\u0e23\u0e37\u0e2d?\u201d \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e44\u0e14\u0e49\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e41\u0e25\u0e30\u0e2d\u0e22\u0e39\u0e48\u0e2a\u0e1a\u0e32\u0e22\u0e08\u0e23\u0e34\u0e07 \u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49 (Adaptation) \u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e01\u0e31\u0e1a\u0e2a\u0e20\u0e32\u0e1e\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e44\u0e17\u0e22:<\/span><\/p>\n<p class=\"ng-star-inserted\"><strong class=\"ng-star-inserted\"><span class=\"ng-star-inserted\">1. \u0e41\u0e01\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32 \u201c\u0e2b\u0e25\u0e31\u0e07\u0e04\u0e32\u0e44\u0e23\u0e49\u0e0a\u0e32\u0e22\u0e04\u0e32\u201d \u0e14\u0e49\u0e27\u0e22\u0e2a\u0e44\u0e15\u0e25\u0e4c Tropical Nordic<\/span><\/strong><br class=\"ng-star-inserted\"><span class=\"ng-star-inserted\">\u0e40\u0e2d\u0e01\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01\u0e04\u0e37\u0e2d\u0e2b\u0e25\u0e31\u0e07\u0e04\u0e32\u0e17\u0e23\u0e07\u0e08\u0e31\u0e48\u0e27\u0e2a\u0e39\u0e07\u0e41\u0e1a\u0e1a\u0e44\u0e21\u0e48\u0e21\u0e35\u0e0a\u0e32\u0e22\u0e04\u0e32 (Barn House) \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e41\u0e15\u0e48\u0e2d\u0e32\u0e08\u0e01\u0e48\u0e2d\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e43\u0e19\u0e44\u0e17\u0e22 \u0e40\u0e0a\u0e48\u0e19 \u0e1d\u0e19\u0e2a\u0e32\u0e14\u0e1c\u0e19\u0e31\u0e07 \u0e41\u0e25\u0e30\u0e19\u0e49\u0e33\u0e23\u0e31\u0e48\u0e27\u0e0b\u0e36\u0e21\u0e15\u0e32\u0e21\u0e02\u0e2d\u0e1a\u0e2b\u0e19\u0e49\u0e32\u0e15\u0e48\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e15\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e16\u0e32\u0e1b\u0e31\u0e15\u0e22\u0e01\u0e23\u0e23\u0e21\u0e40\u0e02\u0e15\u0e23\u0e49\u0e2d\u0e19\u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u00a0<\/span><strong class=\"ng-star-inserted\"><span class=\"ng-star-inserted\">\u201cTropical Nordic\u201d<\/span><\/strong><span class=\"ng-star-inserted\">\u00a0\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e15\u0e34\u0e21\u0e0a\u0e32\u0e22\u0e04\u0e32\u0e22\u0e37\u0e48\u0e19\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e40\u0e25\u0e47\u0e01\u0e19\u0e49\u0e2d\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e23\u0e32\u0e07\u0e19\u0e49\u0e33\u0e1d\u0e19\u0e41\u0e1a\u0e1a\u0e0b\u0e48\u0e2d\u0e19\u0e23\u0e39\u0e1b \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e31\u0e19\u0e1d\u0e19\u0e2a\u0e32\u0e14\u0e42\u0e14\u0e22\u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e04\u0e07\u0e40\u0e2a\u0e49\u0e19\u0e2a\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e41\u0e1a\u0e1a\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01\u0e44\u0e27\u0e49<\/span><\/p>\n<p class=\"ng-star-inserted\"><strong class=\"ng-star-inserted\"><span class=\"ng-star-inserted\">2. \u0e0a\u0e48\u0e2d\u0e07\u0e41\u0e2a\u0e07\u0e1a\u0e32\u0e19\u0e43\u0e2b\u0e0d\u0e48 \u0e15\u0e49\u0e2d\u0e07\u0e21\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e34\u0e28\u0e17\u0e32\u0e07\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e2b\u0e25\u0e31\u0e01<\/span><\/strong><br class=\"ng-star-inserted\"><span class=\"ng-star-inserted\">\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e19\u0e35\u0e49\u0e40\u0e19\u0e49\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14\u0e23\u0e31\u0e1a\u0e41\u0e2a\u0e07\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 (Natural Light) \u0e1c\u0e48\u0e32\u0e19\u0e01\u0e23\u0e30\u0e08\u0e01\u0e1a\u0e32\u0e19\u0e43\u0e2b\u0e0d\u0e48 \u0e41\u0e15\u0e48\u0e41\u0e14\u0e14\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e44\u0e17\u0e22\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e2a\u0e39\u0e07 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19\u00a0<\/span><strong class=\"ng-star-inserted\"><span class=\"ng-star-inserted\">\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e17\u0e34\u0e28\u0e17\u0e32\u0e07\u0e15\u0e31\u0e27\u0e1a\u0e49\u0e32\u0e19<\/span><\/strong><span class=\"ng-star-inserted\">\u00a0\u0e08\u0e36\u0e07\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14<\/span><\/p>\n<ul>\n<li class=\"ng-star-inserted\"><strong class=\"ng-star-inserted\"><span class=\"ng-star-inserted\">\u0e17\u0e34\u0e28\u0e40\u0e2b\u0e19\u0e37\u0e2d:<\/span><\/strong><span class=\"ng-star-inserted\">\u00a0\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e15\u0e34\u0e14\u0e01\u0e23\u0e30\u0e08\u0e01\u0e1a\u0e32\u0e19\u0e43\u0e2b\u0e0d\u0e48 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e41\u0e2a\u0e07\u0e2a\u0e27\u0e48\u0e32\u0e07\u0e15\u0e25\u0e2d\u0e14\u0e27\u0e31\u0e19\u0e41\u0e15\u0e48\u0e44\u0e21\u0e48\u0e23\u0e49\u0e2d\u0e19<\/span><\/li>\n<li class=\"ng-star-inserted\"><strong class=\"ng-star-inserted\"><span class=\"ng-star-inserted\">\u0e17\u0e34\u0e28\u0e15\u0e30\u0e27\u0e31\u0e19\u0e15\u0e01\/\u0e43\u0e15\u0e49:<\/span><\/strong><span class=\"ng-star-inserted\">\u00a0\u0e04\u0e27\u0e23\u0e40\u0e25\u0e35\u0e48\u0e22\u0e07\u0e01\u0e23\u0e30\u0e08\u0e01\u0e43\u0e2b\u0e0d\u0e48 \u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e32\u0e01\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e27\u0e23\u0e43\u0e0a\u0e49\u0e01\u0e23\u0e30\u0e08\u0e01\u0e01\u0e31\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19 (Low-E Glass) \u0e41\u0e25\u0e30\u0e21\u0e35\u0e21\u0e48\u0e32\u0e19\u0e01\u0e23\u0e2d\u0e07\u0e41\u0e2a\u0e07\u0e0a\u0e48\u0e27\u0e22<\/span><\/li>\n<\/ul>\n<p class=\"ng-star-inserted\"><strong class=\"ng-star-inserted\"><span class=\"ng-star-inserted\">3. \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e44\u0e21\u0e49 \u0e01\u0e31\u0e1a \u0e1b\u0e25\u0e27\u0e01\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e37\u0e49\u0e19<\/span><\/strong><br class=\"ng-star-inserted\"><span class=\"ng-star-inserted\">\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e04\u0e37\u0e2d\u0e2b\u0e31\u0e27\u0e43\u0e08\u0e02\u0e2d\u0e07\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01 \u0e41\u0e15\u0e48\u0e07\u0e32\u0e19\u0e44\u0e21\u0e49\u0e08\u0e23\u0e34\u0e07\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e21\u0e31\u0e01\u0e41\u0e1e\u0e49\u0e1d\u0e19\u0e41\u0e25\u0e30\u0e1b\u0e25\u0e27\u0e01\u0e43\u0e19\u0e44\u0e17\u0e22 \u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e17\u0e35\u0e48\u0e04\u0e38\u0e49\u0e21\u0e04\u0e48\u0e32\u0e41\u0e25\u0e30\u0e14\u0e39\u0e41\u0e25\u0e23\u0e31\u0e01\u0e29\u0e32\u0e07\u0e48\u0e32\u0e22\u0e01\u0e27\u0e48\u0e32\u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u00a0<\/span><strong class=\"ng-star-inserted\"><span class=\"ng-star-inserted\">\u201c\u0e44\u0e21\u0e49\u0e40\u0e17\u0e35\u0e22\u0e21\u201d (Wood Substitute)<\/span><\/strong><span class=\"ng-star-inserted\">\u00a0\u0e2b\u0e23\u0e37\u0e2d\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e14\u0e41\u0e17\u0e19\u0e44\u0e21\u0e49\u0e17\u0e35\u0e48\u0e21\u0e35\u0e25\u0e27\u0e14\u0e25\u0e32\u0e22\u0e2a\u0e21\u0e08\u0e23\u0e34\u0e07 \u0e17\u0e19\u0e17\u0e32\u0e19\u0e15\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e37\u0e49\u0e19 \u0e44\u0e21\u0e48\u0e1a\u0e27\u0e21\u0e1e\u0e2d\u0e07 \u0e41\u0e25\u0e30\u0e2b\u0e21\u0e14\u0e01\u0e31\u0e07\u0e27\u0e25\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1b\u0e25\u0e27\u0e01\u0e01\u0e34\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07<\/span><\/p>\n<p class=\"ng-star-inserted\"><strong class=\"ng-star-inserted\"><span class=\"ng-star-inserted\">4. \u0e17\u0e23\u0e07\u0e2b\u0e25\u0e31\u0e07\u0e04\u0e32\u0e2a\u0e39\u0e07 \u0e42\u0e1b\u0e23\u0e48\u0e07 \u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e44\u0e14\u0e49\u0e14\u0e35<\/span><\/strong><br class=\"ng-star-inserted\"><span class=\"ng-star-inserted\">\u0e02\u0e49\u0e2d\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e02\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e1a\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e44\u0e17\u0e22\u0e04\u0e37\u0e2d\u00a0<\/span><strong class=\"ng-star-inserted\"><span class=\"ng-star-inserted\">\u201cHigh Ceiling\u201d<\/span><\/strong><span class=\"ng-star-inserted\">\u00a0\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e1e\u0e14\u0e32\u0e19\u0e17\u0e23\u0e07\u0e08\u0e31\u0e48\u0e27\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07\u0e42\u0e1b\u0e23\u0e48\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e15\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e01\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e04\u0e27\u0e32\u0e21\u0e23\u0e49\u0e2d\u0e19\u0e08\u0e30\u0e25\u0e2d\u0e22\u0e15\u0e31\u0e27\u0e02\u0e36\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e39\u0e07 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e14\u0e49\u0e32\u0e19\u0e25\u0e48\u0e32\u0e07\u0e40\u0e22\u0e47\u0e19\u0e2a\u0e1a\u0e32\u0e22 \u0e2b\u0e32\u0e01\u0e21\u0e35\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e31\u0e49\u0e07\u0e0a\u0e48\u0e2d\u0e07\u0e23\u0e30\u0e1a\u0e32\u0e22\u0e2d\u0e32\u0e01\u0e32\u0e28 (Ventilation) \u0e17\u0e35\u0e48\u0e1a\u0e23\u0e34\u0e40\u0e27\u0e13\u0e43\u0e15\u0e49\u0e2b\u0e25\u0e31\u0e07\u0e04\u0e32\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e14\u0e49\u0e27\u0e22 \u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e22\u0e47\u0e19\u0e02\u0e36\u0e49\u0e19\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e04\u0e48\u0e32\u0e41\u0e2d\u0e23\u0e4c\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01<\/span><\/p>\n<p>\u00a0<\/p>\n<p>\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e43\u0e19\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01\u0e44\u0e21\u0e48\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e15\u0e48\u0e0a\u0e48\u0e27\u0e22\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e41\u0e15\u0e48\u0e22\u0e31\u0e07\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e07\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e2a\u0e1a\u0e32\u0e22\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<br>\n\u0e17\u0e35\u0e48\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e23\u0e2a\u0e34\u0e23\u0e34\u0e19\u0e22\u0e31\u0e07\u0e21\u0e35\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01 \u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e04\u0e23\u0e1a \u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e17\u0e38\u0e01\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u201c<a href=\"https:\/\/ornsirin.co.th\/cn\/property-item\/belive-sansai-maejo\/\">Belive (\u0e2a\u0e31\u0e19\u0e17\u0e23\u0e32\u0e22 \u2013 \u0e41\u0e21\u0e48\u0e42\u0e08\u0e49)<\/a>\u201d \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e14\u0e35\u0e48\u0e22\u0e27\u0e17\u0e33\u0e40\u0e25\u0e14\u0e35 \u0e43\u0e01\u0e25\u0e49\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07 \u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e40\u0e1e\u0e35\u0e22\u0e07 3.5 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17<br>\n\u0e40\u0e2d\u0e01\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e15\u0e31\u0e27 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e02\u0e2d\u0e07 Scandinavian \u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e2d\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e25\u0e41\u0e25\u0e30\u0e41\u0e23\u0e07\u0e1a\u0e31\u0e19\u0e14\u0e32\u0e25\u0e43\u0e08\u0e21\u0e32\u0e08\u0e32\u0e01\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e40\u0e19\u0e49\u0e19\u0e42\u0e17\u0e19\u0e2a\u0e35\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e27\u0e48\u0e32\u0e07\u0e2d\u0e1a\u0e2d\u0e38\u0e48\u0e19<br>\n\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e01\u0e32\u0e23\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e02\u0e2d\u0e07 \u201c\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02\u201d \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02 \u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e17\u0e35\u0e48\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07<\/p>\n<p>\u0e17\u0e35\u0e48\u0e21\u0e32\u0e02\u0e2d\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 : <a href=\"https:\/\/www.bnbhome.com\/th\/articles\/nordic-mood-in-your-home?srsltid=AfmBOopiJbJKm0UQ-uv0gAdQcJq55qRe2QJDpE_jtQjtjbMVWXZzxQMU\">BNBHome<\/a><\/p>\n<p>\u0e41\u0e17\u0e47\u0e01 : \u0e1a\u0e49\u0e32\u0e19 \u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e14\u0e35\u0e48\u0e22\u0e27 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01<\/p>\n<h2 class=\"ng-star-inserted\"><span class=\"ng-star-inserted\">\u0e21\u0e2d\u0e07\u0e2b\u0e32\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e02\u0e32\u0e22\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 \u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01? \u0e40\u0e0a\u0e47\u0e01\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e08\u0e32\u0e01\u0e2d\u0e2d\u0e23\u0e34\u0e49\u0e19\u0e2a\u0e34\u0e23\u0e34\u0e19<\/span><\/h2>\n<p>\u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e01\u0e33\u0e25\u0e31\u0e07\u0e21\u0e2d\u0e07\u0e2b\u0e32\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e19\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23 <strong>\u0e02\u0e32\u0e22\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48<\/strong> \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07 <strong>\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01<\/strong> \u0e2d\u0e2d\u0e23\u0e34\u0e49\u0e19\u0e2a\u0e34\u0e23\u0e34\u0e19\u0e21\u0e35\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e17\u0e31\u0e49\u0e07\u0e1f\u0e31\u0e07\u0e01\u0e4c\u0e0a\u0e31\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e43\u0e19\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e17\u0e33\u0e40\u0e25\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19:<\/p>\n<ul>\n<li><a href=\"https:\/\/ornsirin.co.th\/cn\/project\/belive-sansai-maejo\/\"><strong>Belive (\u0e2a\u0e31\u0e19\u0e17\u0e23\u0e32\u0e22 \u2013 \u0e41\u0e21\u0e48\u0e42\u0e08\u0e49)<\/strong><\/a>: \u0e1a\u0e49\u0e32\u0e19\u0e40\u0e14\u0e35\u0e48\u0e22\u0e27\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e42\u0e1b\u0e23\u0e48\u0e07\u0e2a\u0e1a\u0e32\u0e22 \u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e22\u0e38\u0e04\u0e43\u0e2b\u0e21\u0e48<\/li>\n<li><a href=\"https:\/\/ornsirin.co.th\/cn\/project\/habitat-wongwaen-sankamphaeng\/\"><strong>Habitat (\u0e27\u0e07\u0e41\u0e2b\u0e27\u0e19 \u2013 \u0e2a\u0e31\u0e19\u0e01\u0e33\u0e41\u0e1e\u0e07)<\/strong><\/a>: \u0e1a\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1c\u0e2a\u0e21\u0e1c\u0e2a\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22\u0e41\u0e25\u0e30\u0e01\u0e25\u0e34\u0e48\u0e19\u0e2d\u0e32\u0e22\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e25\u0e07\u0e15\u0e31\u0e27<\/li>\n<\/ul>\n<p>\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e0b\u0e37\u0e49\u0e2d\u0e1a\u0e49\u0e32\u0e19\u0e43\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e21\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e14\u0e35 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e08\u0e30\u0e44\u0e14\u0e49\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21\u0e41\u0e25\u0e49\u0e27 \u0e22\u0e31\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e25\u0e07\u0e17\u0e38\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e15\u0e25\u0e32\u0e14 <strong>\u0e02\u0e32\u0e22\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48<\/strong> \u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22<\/p>\n<p><strong>\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07:<\/strong> <a href=\"https:\/\/ornsirin.co.th\/cn\/diy-nordic-home-decor-ideas\/\">5 \u0e44\u0e2d\u0e40\u0e14\u0e35\u0e22\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01 \u0e43\u0e2b\u0e49\u0e2a\u0e27\u0e22\u0e40\u0e23\u0e35\u0e22\u0e1a \u0e2d\u0e1a\u0e2d\u0e38\u0e48\u0e19 \u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e04\u0e32\u0e40\u0e1f\u0e48\u0e2a\u0e48\u0e27\u0e19\u0e15\u0e31\u0e27<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01 (Nordic Style) \u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e19\u0e31\u0e49\u0e19\u0e21\u0e35\u0e25\u0e31\u0e01\u0e29\u0e13\u0e30\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e35\u0e48\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e16\u0e36\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e07\u0e48\u0e32\u0e22 \u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e2d\u0e32\u0e14\u0e15\u0e32 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e43\u0e01\u0e25\u0e49\u0e0a\u0e34\u0e14\u0e01\u0e31\u0e1a\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e19\u0e35\u0e48\u0e04\u0e37\u0e2d\u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a\u0e43\u0e19\u0e01\u0e32\u0e23\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e43\u0e19\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e19\u0e35\u0e49 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e42\u0e17\u0e19\u0e2a\u0e35: \u0e43\u0e0a\u0e49\u0e42\u0e17\u0e19\u0e2a\u0e35\u0e2d\u0e48\u0e2d\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e02\u0e32\u0e27 \u0e40\u0e17\u0e32 \u0e40\u0e1a\u0e08 \u0e41\u0e25\u0e30\u0e2a\u0e35\u0e19\u0e49\u0e33\u0e40\u0e07\u0e34\u0e19\u0e2d\u0e48\u0e2d\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e17\u0e35\u0e48\u0e2d\u0e1a\u0e2d\u0e38\u0e48\u0e19\u0e41\u0e25\u0e30\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22 \u0e41\u0e2a\u0e07\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34: \u0e43\u0e0a\u0e49\u0e41\u0e2a\u0e07\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e43\u0e2b\u0e49\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e1c\u0e49\u0e32\u0e21\u0e48\u0e32\u0e19\u0e40\u0e1a\u0e32\u0e41\u0e25\u0e30\u0e42\u0e1b\u0e23\u0e48\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e41\u0e2a\u0e07\u0e2a\u0e48\u0e2d\u0e07\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19 \u0e27\u0e31\u0e2a\u0e14\u0e38\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34: \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49\u0e27\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e40\u0e0a\u0e48\u0e19 \u0e44\u0e21\u0e49 \u0e2b\u0e19\u0e31\u0e07 \u0e41\u0e25\u0e30\u0e1b\u0e39\u0e19\u0e02\u0e32\u0e27 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e2d\u0e1a\u0e2d\u0e38\u0e48\u0e19 \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e07\u0e48\u0e32\u0e22: \u0e40\u0e1f\u0e2d\u0e23\u0e4c\u0e19\u0e34\u0e40\u0e08\u0e2d\u0e23\u0e4c\u0e04\u0e27\u0e23\u0e21\u0e35\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e07\u0e48\u0e32\u0e22\u0e41\u0e25\u0e30\u0e1f\u0e31\u0e07\u0e01\u0e4c\u0e0a\u0e31\u0e19\u0e17\u0e35\u0e48\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e42\u0e15\u0e4a\u0e30\u0e44\u0e21\u0e49\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e2a\u0e41\u0e01\u0e19\u0e14\u0e34\u0e40\u0e19\u0e40\u0e27\u0e35\u0e22 \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22: \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e17\u0e33\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e19 \u0e21\u0e38\u0e21\u0e2d\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e2b\u0e23\u0e37\u0e2d\u0e21\u0e38\u0e21\u0e17\u0e33\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e30\u0e14\u0e27\u0e01 \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e14\u0e49\u0e27\u0e22\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49: \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1e\u0e37\u0e0a\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e2a\u0e14\u0e0a\u0e37\u0e48\u0e19\u0e41\u0e25\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e1f\u0e2d\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28 \u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e07\u0e32\u0e19\u0e1d\u0e35\u0e21\u0e37\u0e2d: \u0e43\u0e0a\u0e49\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e2b\u0e23\u0e37\u0e2d\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e07\u0e32\u0e19\u0e1d\u0e35\u0e21\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e21\u0e35\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e19\u0e49\u0e2d\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e2d\u0e01\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e40\u0e2a\u0e23\u0e34\u0e21: \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e14\u0e35\u0e44\u0e0b\u0e19\u0e4c\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e07\u0e48\u0e32\u0e22 \u0e40\u0e0a\u0e48\u0e19 \u0e42\u0e04\u0e21\u0e44\u0e1f\u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e23\u0e21\u0e17\u0e35\u0e48\u0e40\u0e19\u0e49\u0e19\u0e42\u0e17\u0e19\u0e2a\u0e35\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u201c\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01\u201d \u0e01\u0e31\u0e1a\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e44\u0e17\u0e22: 4 [&hellip;]<\/p>","protected":false},"author":8,"featured_media":40304,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[104],"tags":[115,223,181,180],"class_list":["post-40305","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-104","tag-115","tag-223","tag-181","tag-180"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.9 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u4e2d\u6587: \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01 8 \u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a\u0e07\u0e48\u0e32\u0e22\u0e46 | \u0e2d\u0e23\u0e28\u0e34\u0e23\u0e34\u0e19\u0e01\u0e23\u0e38\u0e4a\u0e1b<\/title>\n<meta name=\"description\" content=\"\u4e2d\u6587: \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e43\u0e19\u0e44\u0e2a\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e07\u0e1a \u0e40\u0e23\u0e35\u0e22\u0e1a\u0e07\u0e48\u0e32\u0e22 \u0e15\u0e32\u0e21\u0e41\u0e1a\u0e1a\u0e09\u0e1a\u0e31\u0e1a\u0e22\u0e38\u0e42\u0e23\u0e1b \u0e17\u0e33\u0e40\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e44\u0e21\u0e48\u0e01\u0e35\u0e48\u0e27\u0e34\u0e18\u0e35 #\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 #\u0e1a\u0e49\u0e32\u0e19 #\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e14\u0e35\u0e48\u0e22\u0e27\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ornsirin.co.th\/cn\/\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e44\u0e15\u0e25\u0e4c Nordic 8 \u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e14\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e07\u0e48\u0e32\u0e22 \u0e41\u0e15\u0e48\u0e41\u0e1d\u0e07\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e44\u0e15\u0e25\u0e4c\" \/>\n<meta property=\"og:description\" content=\"\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e43\u0e19\u0e44\u0e2a\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e07\u0e1a \u0e40\u0e23\u0e35\u0e22\u0e1a\u0e07\u0e48\u0e32\u0e22 \u0e15\u0e32\u0e21\u0e41\u0e1a\u0e1a\u0e09\u0e1a\u0e31\u0e1a\u0e22\u0e38\u0e42\u0e23\u0e1b \u0e17\u0e33\u0e40\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e44\u0e21\u0e48\u0e01\u0e35\u0e48\u0e27\u0e34\u0e18\u0e35 #\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 #\u0e1a\u0e49\u0e32\u0e19 #\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e14\u0e35\u0e48\u0e22\u0e27\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ornsirin.co.th\/cn\/\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\/\" \/>\n<meta property=\"og:site_name\" content=\"Ornsirin (ORN)\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ornsirin.chiangmai\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-21T04:23:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-17T14:57:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ornsirin.co.th\/wp-content\/uploads\/2024\/10\/\u0e1a\u0e49\u0e32\u0e19\u0e44\u0e2a\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1703\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Methas Suvanpahu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"Methas Suvanpahu\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 \u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ornsirin.co.th\\\/%e0%b8%95%e0%b8%81%e0%b9%81%e0%b8%95%e0%b9%88%e0%b8%87%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ornsirin.co.th\\\/%e0%b8%95%e0%b8%81%e0%b9%81%e0%b8%95%e0%b9%88%e0%b8%87%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99\\\/\"},\"author\":{\"name\":\"Methas Suvanpahu\",\"@id\":\"https:\\\/\\\/ornsirin.co.th\\\/#\\\/schema\\\/person\\\/f57074d9173d85d38c058e16c42a0ab0\"},\"headline\":\"\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e44\u0e15\u0e25\u0e4c Nordic 8 \u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e14\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e07\u0e48\u0e32\u0e22 \u0e41\u0e15\u0e48\u0e41\u0e1d\u0e07\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e44\u0e15\u0e25\u0e4c\",\"datePublished\":\"2024-10-21T04:23:34+00:00\",\"dateModified\":\"2026-03-17T14:57:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ornsirin.co.th\\\/%e0%b8%95%e0%b8%81%e0%b9%81%e0%b8%95%e0%b9%88%e0%b8%87%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99\\\/\"},\"wordCount\":26,\"publisher\":{\"@id\":\"https:\\\/\\\/ornsirin.co.th\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ornsirin.co.th\\\/%e0%b8%95%e0%b8%81%e0%b9%81%e0%b8%95%e0%b9%88%e0%b8%87%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ornsirin.co.th\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/\u0e1a\u0e49\u0e32\u0e19\u0e44\u0e2a\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01-scaled.webp\",\"keywords\":[\"\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\",\"\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01\",\"\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e14\u0e35\u0e48\u0e22\u0e27\",\"\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48\"],\"articleSection\":[\"\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\"],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ornsirin.co.th\\\/%e0%b8%95%e0%b8%81%e0%b9%81%e0%b8%95%e0%b9%88%e0%b8%87%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99\\\/\",\"url\":\"https:\\\/\\\/ornsirin.co.th\\\/%e0%b8%95%e0%b8%81%e0%b9%81%e0%b8%95%e0%b9%88%e0%b8%87%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99\\\/\",\"name\":\"\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01 8 \u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a\u0e07\u0e48\u0e32\u0e22\u0e46 | \u0e2d\u0e23\u0e28\u0e34\u0e23\u0e34\u0e19\u0e01\u0e23\u0e38\u0e4a\u0e1b\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ornsirin.co.th\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ornsirin.co.th\\\/%e0%b8%95%e0%b8%81%e0%b9%81%e0%b8%95%e0%b9%88%e0%b8%87%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ornsirin.co.th\\\/%e0%b8%95%e0%b8%81%e0%b9%81%e0%b8%95%e0%b9%88%e0%b8%87%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ornsirin.co.th\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/\u0e1a\u0e49\u0e32\u0e19\u0e44\u0e2a\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01-scaled.webp\",\"datePublished\":\"2024-10-21T04:23:34+00:00\",\"dateModified\":\"2026-03-17T14:57:08+00:00\",\"description\":\"\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e43\u0e19\u0e44\u0e2a\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e07\u0e1a \u0e40\u0e23\u0e35\u0e22\u0e1a\u0e07\u0e48\u0e32\u0e22 \u0e15\u0e32\u0e21\u0e41\u0e1a\u0e1a\u0e09\u0e1a\u0e31\u0e1a\u0e22\u0e38\u0e42\u0e23\u0e1b \u0e17\u0e33\u0e40\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e44\u0e21\u0e48\u0e01\u0e35\u0e48\u0e27\u0e34\u0e18\u0e35 #\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 #\u0e1a\u0e49\u0e32\u0e19 #\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e14\u0e35\u0e48\u0e22\u0e27\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ornsirin.co.th\\\/%e0%b8%95%e0%b8%81%e0%b9%81%e0%b8%95%e0%b9%88%e0%b8%87%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ornsirin.co.th\\\/%e0%b8%95%e0%b8%81%e0%b9%81%e0%b8%95%e0%b9%88%e0%b8%87%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/ornsirin.co.th\\\/%e0%b8%95%e0%b8%81%e0%b9%81%e0%b8%95%e0%b9%88%e0%b8%87%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ornsirin.co.th\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/\u0e1a\u0e49\u0e32\u0e19\u0e44\u0e2a\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/ornsirin.co.th\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/\u0e1a\u0e49\u0e32\u0e19\u0e44\u0e2a\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01-scaled.webp\",\"width\":2560,\"height\":1703,\"caption\":\"\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01 8 \u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a\u0e07\u0e48\u0e32\u0e22\u0e46\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ornsirin.co.th\\\/%e0%b8%95%e0%b8%81%e0%b9%81%e0%b8%95%e0%b9%88%e0%b8%87%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ornsirin.co.th\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e44\u0e15\u0e25\u0e4c Nordic 8 \u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e14\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e07\u0e48\u0e32\u0e22 \u0e41\u0e15\u0e48\u0e41\u0e1d\u0e07\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e44\u0e15\u0e25\u0e4c\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ornsirin.co.th\\\/#website\",\"url\":\"https:\\\/\\\/ornsirin.co.th\\\/\",\"name\":\"Ornsirin \u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e17\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2e\u0e21 \u0e0a\u0e47\u0e2d\u0e1b\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c (ORN)\",\"description\":\"\u0e1a\u0e49\u0e32\u0e19 \u0e17\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2e\u0e21 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e19\u0e34\u0e0a\u0e13\u0e4c \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e38\u0e13\",\"publisher\":{\"@id\":\"https:\\\/\\\/ornsirin.co.th\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ornsirin.co.th\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ornsirin.co.th\\\/#organization\",\"name\":\"Ornsirin (ORN)\",\"url\":\"https:\\\/\\\/ornsirin.co.th\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/ornsirin.co.th\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ornsirin.co.th\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Logo-italic-1.png\",\"contentUrl\":\"https:\\\/\\\/ornsirin.co.th\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Logo-italic-1.png\",\"width\":304,\"height\":174,\"caption\":\"Ornsirin (ORN)\"},\"image\":{\"@id\":\"https:\\\/\\\/ornsirin.co.th\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ornsirin.chiangmai\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ornsirin.co.th\\\/#\\\/schema\\\/person\\\/f57074d9173d85d38c058e16c42a0ab0\",\"name\":\"Methas Suvanpahu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/451f0e6090d750b68ae371d950f1fc42457ad66db68dd3e9ccfde4d6738bc872?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/451f0e6090d750b68ae371d950f1fc42457ad66db68dd3e9ccfde4d6738bc872?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/451f0e6090d750b68ae371d950f1fc42457ad66db68dd3e9ccfde4d6738bc872?s=96&d=mm&r=g\",\"caption\":\"Methas Suvanpahu\"},\"url\":\"https:\\\/\\\/ornsirin.co.th\\\/cn\\\/author\\\/ornsiri7_12\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u4e2d\u6587: \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01 8 \u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a\u0e07\u0e48\u0e32\u0e22\u0e46 | \u0e2d\u0e23\u0e28\u0e34\u0e23\u0e34\u0e19\u0e01\u0e23\u0e38\u0e4a\u0e1b","description":"\u4e2d\u6587: \u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e43\u0e19\u0e44\u0e2a\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e07\u0e1a \u0e40\u0e23\u0e35\u0e22\u0e1a\u0e07\u0e48\u0e32\u0e22 \u0e15\u0e32\u0e21\u0e41\u0e1a\u0e1a\u0e09\u0e1a\u0e31\u0e1a\u0e22\u0e38\u0e42\u0e23\u0e1b \u0e17\u0e33\u0e40\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e44\u0e21\u0e48\u0e01\u0e35\u0e48\u0e27\u0e34\u0e18\u0e35 #\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 #\u0e1a\u0e49\u0e32\u0e19 #\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e14\u0e35\u0e48\u0e22\u0e27","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ornsirin.co.th\/cn\/\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\/","og_locale":"zh_CN","og_type":"article","og_title":"\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e44\u0e15\u0e25\u0e4c Nordic 8 \u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e14\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e07\u0e48\u0e32\u0e22 \u0e41\u0e15\u0e48\u0e41\u0e1d\u0e07\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e44\u0e15\u0e25\u0e4c","og_description":"\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e43\u0e19\u0e44\u0e2a\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e07\u0e1a \u0e40\u0e23\u0e35\u0e22\u0e1a\u0e07\u0e48\u0e32\u0e22 \u0e15\u0e32\u0e21\u0e41\u0e1a\u0e1a\u0e09\u0e1a\u0e31\u0e1a\u0e22\u0e38\u0e42\u0e23\u0e1b \u0e17\u0e33\u0e40\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e44\u0e21\u0e48\u0e01\u0e35\u0e48\u0e27\u0e34\u0e18\u0e35 #\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 #\u0e1a\u0e49\u0e32\u0e19 #\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e14\u0e35\u0e48\u0e22\u0e27","og_url":"https:\/\/ornsirin.co.th\/cn\/\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\/","og_site_name":"Ornsirin (ORN)","article_publisher":"https:\/\/www.facebook.com\/ornsirin.chiangmai\/","article_published_time":"2024-10-21T04:23:34+00:00","article_modified_time":"2026-03-17T14:57:08+00:00","og_image":[{"width":2560,"height":1703,"url":"https:\/\/ornsirin.co.th\/wp-content\/uploads\/2024\/10\/\u0e1a\u0e49\u0e32\u0e19\u0e44\u0e2a\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01-scaled.webp","type":"image\/webp"}],"author":"Methas Suvanpahu","twitter_card":"summary_large_image","twitter_misc":{"\u4f5c\u8005":"Methas Suvanpahu","\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"2 \u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ornsirin.co.th\/%e0%b8%95%e0%b8%81%e0%b9%81%e0%b8%95%e0%b9%88%e0%b8%87%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99\/#article","isPartOf":{"@id":"https:\/\/ornsirin.co.th\/%e0%b8%95%e0%b8%81%e0%b9%81%e0%b8%95%e0%b9%88%e0%b8%87%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99\/"},"author":{"name":"Methas Suvanpahu","@id":"https:\/\/ornsirin.co.th\/#\/schema\/person\/f57074d9173d85d38c058e16c42a0ab0"},"headline":"\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e44\u0e15\u0e25\u0e4c Nordic 8 \u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e14\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e07\u0e48\u0e32\u0e22 \u0e41\u0e15\u0e48\u0e41\u0e1d\u0e07\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e44\u0e15\u0e25\u0e4c","datePublished":"2024-10-21T04:23:34+00:00","dateModified":"2026-03-17T14:57:08+00:00","mainEntityOfPage":{"@id":"https:\/\/ornsirin.co.th\/%e0%b8%95%e0%b8%81%e0%b9%81%e0%b8%95%e0%b9%88%e0%b8%87%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99\/"},"wordCount":26,"publisher":{"@id":"https:\/\/ornsirin.co.th\/#organization"},"image":{"@id":"https:\/\/ornsirin.co.th\/%e0%b8%95%e0%b8%81%e0%b9%81%e0%b8%95%e0%b9%88%e0%b8%87%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99\/#primaryimage"},"thumbnailUrl":"https:\/\/ornsirin.co.th\/wp-content\/uploads\/2024\/10\/\u0e1a\u0e49\u0e32\u0e19\u0e44\u0e2a\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01-scaled.webp","keywords":["\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19","\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01","\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e14\u0e35\u0e48\u0e22\u0e27","\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48"],"articleSection":["\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21"],"inLanguage":"zh-Hans"},{"@type":"WebPage","@id":"https:\/\/ornsirin.co.th\/%e0%b8%95%e0%b8%81%e0%b9%81%e0%b8%95%e0%b9%88%e0%b8%87%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99\/","url":"https:\/\/ornsirin.co.th\/%e0%b8%95%e0%b8%81%e0%b9%81%e0%b8%95%e0%b9%88%e0%b8%87%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99\/","name":"\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07 \u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01 8 \u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a\u0e07\u0e48\u0e32\u0e22\u0e46 | \u0e2d\u0e23\u0e28\u0e34\u0e23\u0e34\u0e19\u0e01\u0e23\u0e38\u0e4a\u0e1b","isPartOf":{"@id":"https:\/\/ornsirin.co.th\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ornsirin.co.th\/%e0%b8%95%e0%b8%81%e0%b9%81%e0%b8%95%e0%b9%88%e0%b8%87%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99\/#primaryimage"},"image":{"@id":"https:\/\/ornsirin.co.th\/%e0%b8%95%e0%b8%81%e0%b9%81%e0%b8%95%e0%b9%88%e0%b8%87%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99\/#primaryimage"},"thumbnailUrl":"https:\/\/ornsirin.co.th\/wp-content\/uploads\/2024\/10\/\u0e1a\u0e49\u0e32\u0e19\u0e44\u0e2a\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01-scaled.webp","datePublished":"2024-10-21T04:23:34+00:00","dateModified":"2026-03-17T14:57:08+00:00","description":"\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e43\u0e19\u0e44\u0e2a\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e07\u0e1a \u0e40\u0e23\u0e35\u0e22\u0e1a\u0e07\u0e48\u0e32\u0e22 \u0e15\u0e32\u0e21\u0e41\u0e1a\u0e1a\u0e09\u0e1a\u0e31\u0e1a\u0e22\u0e38\u0e42\u0e23\u0e1b \u0e17\u0e33\u0e40\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e44\u0e21\u0e48\u0e01\u0e35\u0e48\u0e27\u0e34\u0e18\u0e35 #\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e0a\u0e35\u0e22\u0e07\u0e43\u0e2b\u0e21\u0e48 #\u0e1a\u0e49\u0e32\u0e19 #\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e14\u0e35\u0e48\u0e22\u0e27","breadcrumb":{"@id":"https:\/\/ornsirin.co.th\/%e0%b8%95%e0%b8%81%e0%b9%81%e0%b8%95%e0%b9%88%e0%b8%87%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ornsirin.co.th\/%e0%b8%95%e0%b8%81%e0%b9%81%e0%b8%95%e0%b9%88%e0%b8%87%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99\/"]}]},{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/ornsirin.co.th\/%e0%b8%95%e0%b8%81%e0%b9%81%e0%b8%95%e0%b9%88%e0%b8%87%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99\/#primaryimage","url":"https:\/\/ornsirin.co.th\/wp-content\/uploads\/2024\/10\/\u0e1a\u0e49\u0e32\u0e19\u0e44\u0e2a\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01-scaled.webp","contentUrl":"https:\/\/ornsirin.co.th\/wp-content\/uploads\/2024\/10\/\u0e1a\u0e49\u0e32\u0e19\u0e44\u0e2a\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01-scaled.webp","width":2560,"height":1703,"caption":"\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e19\u0e2d\u0e23\u0e4c\u0e14\u0e34\u0e01 8 \u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a\u0e07\u0e48\u0e32\u0e22\u0e46"},{"@type":"BreadcrumbList","@id":"https:\/\/ornsirin.co.th\/%e0%b8%95%e0%b8%81%e0%b9%81%e0%b8%95%e0%b9%88%e0%b8%87%e0%b8%9a%e0%b9%89%e0%b8%b2%e0%b8%99\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ornsirin.co.th\/"},{"@type":"ListItem","position":2,"name":"\u0e15\u0e01\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e2a\u0e44\u0e15\u0e25\u0e4c Nordic 8 \u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e41\u0e15\u0e48\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e2a\u0e38\u0e14\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e07\u0e48\u0e32\u0e22 \u0e41\u0e15\u0e48\u0e41\u0e1d\u0e07\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e44\u0e15\u0e25\u0e4c"}]},{"@type":"WebSite","@id":"https:\/\/ornsirin.co.th\/#website","url":"https:\/\/ornsirin.co.th\/","name":"Ornsirin \u0e1a\u0e49\u0e32\u0e19 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e17\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2e\u0e21 \u0e0a\u0e47\u0e2d\u0e1b\u0e40\u0e2e\u0e49\u0e32\u0e2a\u0e4c (ORN)","description":"\u0e1a\u0e49\u0e32\u0e19 \u0e17\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2e\u0e21 \u0e04\u0e2d\u0e19\u0e42\u0e14 \u0e2d\u0e32\u0e04\u0e32\u0e23\u0e1e\u0e32\u0e19\u0e34\u0e0a\u0e13\u0e4c \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e38\u0e13","publisher":{"@id":"https:\/\/ornsirin.co.th\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ornsirin.co.th\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":"Organization","@id":"https:\/\/ornsirin.co.th\/#organization","name":"Ornsirin (ORN)","url":"https:\/\/ornsirin.co.th\/","logo":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/ornsirin.co.th\/#\/schema\/logo\/image\/","url":"https:\/\/ornsirin.co.th\/wp-content\/uploads\/2024\/08\/Logo-italic-1.png","contentUrl":"https:\/\/ornsirin.co.th\/wp-content\/uploads\/2024\/08\/Logo-italic-1.png","width":304,"height":174,"caption":"Ornsirin (ORN)"},"image":{"@id":"https:\/\/ornsirin.co.th\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ornsirin.chiangmai\/"]},{"@type":"Person","@id":"https:\/\/ornsirin.co.th\/#\/schema\/person\/f57074d9173d85d38c058e16c42a0ab0","name":"Methas Suvanpahu","image":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/secure.gravatar.com\/avatar\/451f0e6090d750b68ae371d950f1fc42457ad66db68dd3e9ccfde4d6738bc872?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/451f0e6090d750b68ae371d950f1fc42457ad66db68dd3e9ccfde4d6738bc872?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/451f0e6090d750b68ae371d950f1fc42457ad66db68dd3e9ccfde4d6738bc872?s=96&d=mm&r=g","caption":"Methas Suvanpahu"},"url":"https:\/\/ornsirin.co.th\/cn\/author\/ornsiri7_12\/"}]}},"_links":{"self":[{"href":"https:\/\/ornsirin.co.th\/cn\/wp-json\/wp\/v2\/posts\/40305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ornsirin.co.th\/cn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ornsirin.co.th\/cn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ornsirin.co.th\/cn\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/ornsirin.co.th\/cn\/wp-json\/wp\/v2\/comments?post=40305"}],"version-history":[{"count":0,"href":"https:\/\/ornsirin.co.th\/cn\/wp-json\/wp\/v2\/posts\/40305\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ornsirin.co.th\/cn\/wp-json\/wp\/v2\/media\/40304"}],"wp:attachment":[{"href":"https:\/\/ornsirin.co.th\/cn\/wp-json\/wp\/v2\/media?parent=40305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ornsirin.co.th\/cn\/wp-json\/wp\/v2\/categories?post=40305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ornsirin.co.th\/cn\/wp-json\/wp\/v2\/tags?post=40305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}